﻿{"id":23764,"date":"2024-10-08T14:10:00","date_gmt":"2024-10-08T16:10:00","guid":{"rendered":"http:\/\/www.harasvistaverde.com.br\/blog\/?p=23764"},"modified":"2024-10-12T14:11:20","modified_gmt":"2024-10-12T16:11:20","slug":"challenger-na-argentina-uma-super-experiencia","status":"publish","type":"post","link":"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/10\/08\/challenger-na-argentina-uma-super-experiencia\/","title":{"rendered":"Challenger na Argentina, uma super experi\u00eancia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/argentina.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"600\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/argentina.jpg\" alt=\"\" class=\"wp-image-23765\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/argentina.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/argentina-300x300.jpg 300w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/argentina-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Participamos dos dois dias do CHALLENGER ARGENTINO e vivemos uma experi\u00eancia muito importante. Primeiro pelo entusiasmo e a quantidade de pessoas que participaram como p\u00fablico. Lotado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/challenger-4.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"328\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/challenger-4.jpg\" alt=\"\" class=\"wp-image-23767\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/challenger-4.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/challenger-4-300x164.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Tamb\u00e9m maravilhoso, e uma enorme alegria ver dois animais vendidos no nosso Leil\u00e3o Vista Verde &amp; Amigos, vencerem por l\u00e1.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/impactante-2.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"400\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/impactante-2.jpg\" alt=\"\" class=\"wp-image-23768\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/impactante-2.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/impactante-2-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<ul><li>IMPACTANTE SECRETS, filho de NO SECRETS HERE, que venceu a prova dos Potrillos QM Ger 2021 nos 325 metros, criado pelo Haras San Jorge, e<\/li><li>DAGO (nome de registro KADRON CORONA), que venceu o p\u00e1reo dos 200m, criado pelo Haras Ja Se Vieram da fam\u00edlia Abravanel.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/imapactante-3.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"443\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/imapactante-3.jpg\" alt=\"\" class=\"wp-image-23769\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/imapactante-3.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/imapactante-3-300x222.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Esse \u00e9 o Jeito Vista Verde de fazer amizades e compartilhar vit\u00f3rias.<\/p>\n\n\n\n<p>N\u00e3o perca nosso pr\u00f3ximo LEIL\u00c3O VISTA VERDE &amp; AMIGOS no dia 15\/03\/2025, no Jockey Club de Sorocaba, junto com o Grande Pr\u00eamio Torneio In\u00edcio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participamos dos dois dias do CHALLENGER ARGENTINO e vivemos uma experi\u00eancia muito importante. Primeiro pelo entusiasmo e a quantidade de pessoas que participaram como p\u00fablico. Lotado. Tamb\u00e9m maravilhoso, e uma enorme alegria ver dois animais vendidos no nosso Leil\u00e3o Vista Verde &amp; Amigos, vencerem por l\u00e1. IMPACTANTE SECRETS, filho de NO SECRETS HERE, que venceu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/23764"}],"collection":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/comments?post=23764"}],"version-history":[{"count":1,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/23764\/revisions"}],"predecessor-version":[{"id":23770,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/23764\/revisions\/23770"}],"wp:attachment":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/media?parent=23764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/categories?post=23764"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/tags?post=23764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}