﻿{"id":23760,"date":"2024-10-12T13:41:44","date_gmt":"2024-10-12T15:41:44","guid":{"rendered":"http:\/\/www.harasvistaverde.com.br\/blog\/?p=23760"},"modified":"2024-10-12T14:44:15","modified_gmt":"2024-10-12T16:44:15","slug":"edberg-verde-corre-grupo-1-esta-madrugada","status":"publish","type":"post","link":"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/10\/12\/edberg-verde-corre-grupo-1-esta-madrugada\/","title":{"rendered":"EDBERG VERDE corre Grupo 1 esta madrugada"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"600\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg.jpg\" alt=\"\" class=\"wp-image-23761\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg-300x300.jpg 300w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Hoje de madrugada, <strong>Edberg Verde <\/strong>volta \u00e0 pista para correr junto com os maiores cavalos da atualidade no Mundo, o ROBERT L. BONIFACE INVITATIONAL CHAMPIONSHIP STAKES &#8211; GRUPO 1.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/robert-edberg.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"201\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/robert-edberg.jpg\" alt=\"\" class=\"wp-image-23778\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/robert-edberg.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/robert-edberg-300x101.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>O astro brasileiro <strong>Edberg Verde<\/strong>, o Quarto de Milha mais rico de todos os tempos no Brasil, largar\u00e1 na baliza # 7. Propriedade de Royal Verde (parceria do Royal Ranch com o Haras Vista Verde) e treinado por Paul Jones, Edberg Verde subiu para o terceiro lugar no Go Man Go e tamb\u00e9m ganhou dois allownces. Ele mostrou boa velocidade em tr\u00eas de suas cinco largadas nos Estados Unidos e precisar\u00e1 fazer isso novamente para ser um fator decisivo em sua primeira corrida nos 402 metros nos EUA.<\/p>\n\n\n\n<p>O p\u00e1reo acontecer\u00e1 na madrugada de s\u00e1bado para domingo \u00e0 01:31hs (hor\u00e1rio de Bras\u00edlia), com transmiss\u00e3o ao vivo no canal do YouTube de Los Alamitos.<\/p>\n\n\n\n<p>\u00c9 o Brasil correndo nas principais pistas de corrida do mundo.<\/p>\n\n\n\n<p>Parab\u00e9ns a Fam\u00edlia Dalmolin pela coragem de enfrentar novamente o multimilion\u00e1rio Empressum, campe\u00e3o mundial da AQHA em 2022, que tentar\u00e1 se tornar o primeiro vencedor consecutivo do Robert Boniface Los Alamitos Invitational Championship Grupo 1, desde 2017. Empressum venceu esta corrida no ano passado por \u00be de dist\u00e2ncia sobre o grande Apolitical Pence e Bomb Cyclone.<\/p>\n\n\n\n<p>EMPRESSUM, castrado de 6 anos filho de Apollitical Jess venceu 24 das 34 partidas, ao mesmo tempo que ganhou $ 2.136.623. Em sua campanha, ele venceu um total de 10 Grande Pr\u00eamios de Grupo 1, sete deles em Los Alamitos. Este ano, Empressum j\u00e1 venceu o Grupo 1 Vessels Maturity e o Grupo 1 Go Man Go Handicap, mas essa vit\u00f3ria veio depois que Jeriko de Bobby Cox foi desclassificado do primeiro e do segundo lugar devido a interfer\u00eancia.<\/p>\n\n\n\n<p>JERIKO, que tamb\u00e9m estar\u00e1 presente nesta corrida desta noite. Jeriko se saiu bem em Los Alamitos. Sua campanha inclui uma vit\u00f3ria no Super Derby de Los Alamitos Grupo 1 e um segundo lugar no Vessels Maturity \u2013 Grpo 1, e no Los Alamitos Two Million Futurity Grupo 1. Ele \u00e9 castrado de 4 anos filho de One Famous. Tem grande recupera\u00e7\u00e3o no final.<\/p>\n\n\n\n<p>O Robert Boniface oferecer\u00e1 uma bolsa de US$ 90.000, com o vencedor ganhando uma poss\u00edvel vaga para o Campe\u00e3o dos Campe\u00f5es de US$ 600.000 Grupo 1 em 14 de dezembro.<\/p>\n\n\n\n<p>Scoops Dynasty de Edward e Von Zae McNelis tem uma longa hist\u00f3ria de sucesso em Los Alamitos e at\u00e9 derrotou Empressum no Go Man Go Handicap do ano passado. Tem 5 anos e \u00e9 filho de FDD DYNATY.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg-robert.jpg\" ><img loading=\"lazy\" width=\"540\" height=\"540\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg-robert.jpg\" alt=\"\" class=\"wp-image-23762\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg-robert.jpg 540w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg-robert-300x300.jpg 300w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/10\/edberg-robert-150x150.jpg 150w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hoje de madrugada, Edberg Verde volta \u00e0 pista para correr junto com os maiores cavalos da atualidade no Mundo, o ROBERT L. BONIFACE INVITATIONAL CHAMPIONSHIP STAKES &#8211; GRUPO 1. O astro brasileiro Edberg Verde, o Quarto de Milha mais rico de todos os tempos no Brasil, largar\u00e1 na baliza # 7. Propriedade de Royal Verde [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/23760"}],"collection":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/comments?post=23760"}],"version-history":[{"count":2,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/23760\/revisions"}],"predecessor-version":[{"id":23779,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/23760\/revisions\/23779"}],"wp:attachment":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/media?parent=23760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/categories?post=23760"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/tags?post=23760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}