﻿{"id":22331,"date":"2024-02-26T13:39:35","date_gmt":"2024-02-26T15:39:35","guid":{"rendered":"http:\/\/www.harasvistaverde.com.br\/blog\/?p=22331"},"modified":"2024-02-26T13:39:37","modified_gmt":"2024-02-26T15:39:37","slug":"hoteis-disponiveis-para-o-leilao-vista-verde","status":"publish","type":"post","link":"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/02\/26\/hoteis-disponiveis-para-o-leilao-vista-verde\/","title":{"rendered":"Hot\u00e9is dispon\u00edveis para o Leil\u00e3o Vista Verde"},"content":{"rendered":"\n<p>Dia 09\/03\/2024 &#8211; s\u00e1bado, acontecer\u00e1 o <strong>Leil\u00e3o Vista Verde &amp; Amigos 2024<\/strong>, no Jockey Club de Sorocaba, junto com as classificat\u00f3rias do <strong>GRANDE PR\u00caMIO &#8211; TORNEIO IN\u00cdCIO, e do GRANDE PR\u00caMIO I DERBY.<\/strong><\/p>\n\n\n\n<p>O Torneio In\u00edcio \u00e9 para potros in\u00e9ditos e o I DERBY para cavalos de 3 ou mais anos, com bosa de R$ 250.000,00 e R$ 150.000,00 respectivamente.<\/p>\n\n\n\n<p>Na quarta-feira dia 06\/03, os animais chegar\u00e3o ao tatersall do Jockey Club de Sorocaba e pode\u00e3o ser vistoriados j\u00e1 na quinta feira di 07.<\/p>\n\n\n\n<p>No dia 08\/03 &#8211; sexta-feira, faremos um churrasco com a apresenta\u00e7\u00e3o de todos os potros que ser\u00e3o vendidos no dia seguinte. A noite haver\u00e1 o enfrene com a defini\u00e7\u00e3o dos p\u00e1reos e no s\u00e1bado as classificat\u00f3rias e na sequencia o Leil\u00e3o.<\/p>\n\n\n\n<p>Voc\u00ea poder\u00e1 fazer sua reserva nos hot\u00e9is que preferir para vir ao Leil\u00e3o, j\u00e1 negociamos por voc\u00ea.<\/p>\n\n\n\n<p><strong><u>HOTEIS SUGERIDOS PARA RESERVA DURANTE SUA ESTADIA PARA O LEIL\u00c3O VISTA VERDE E AMIGOS \u2013 09\/03\/24<\/u><\/strong><\/p>\n\n\n\n<p><strong><u>Meu Hotel Boituva<\/u><\/strong><\/p>\n\n\n\n<ul><li>Endere\u00e7o: R. Ant\u00f4nio A. Amadio, 261 &#8211; Centro Empresarial Castello Branco, Boituva<\/li><li>Telefone para Reserva (15) 3264 2100<\/li><li>Di\u00e1ria Single: R$ 217,00<\/li><li>Di\u00e1ria Casal: R$ 297,00<\/li><li>Mencionar que \u00e9 para o Leil\u00e3o Vista Verde e Amigos<\/li><li>Dist\u00e2ncia Hotel x JCS \u2013 32.8 km<\/li><\/ul>\n\n\n\n<p><strong><u>Hotel Toyo Inn<\/u><\/strong><\/p>\n\n\n\n<ul><li>Endere\u00e7o: Av. M\u00e1rio Pedro Vercellino, 238 &#8211; Ch\u00e1cara Labronci, Boituva<\/li><li>Telefone para Reserva (15) 3268 9100<\/li><li>Di\u00e1ria Single (Standart): R$ 169,00<\/li><li>Di\u00e1ria Casal (Standart): \u00a0R$ 219,00<\/li><li>Di\u00e1ria Triplo (Standart): R$ 269,00<\/li><li>Mencionar que \u00e9 para o Leil\u00e3o Vista Verde e Amigos<\/li><li>OBS = Toy Inn com poucos aptos dispon\u00edveis para a data, motivo evento de paraquedismo e no Grupo Petr\u00f3polis.<\/li><li>Dist\u00e2ncia Hotel x JCS &#8211; 35.3 km<\/li><\/ul>\n\n\n\n<p><strong><u>Hotel All Inn Sorocaba<\/u><\/strong><\/p>\n\n\n\n<ul><li>Endere\u00e7o: Av. Eng. Carlos Reinaldo Mendes, 3541 &#8211; Jardim Pelegrino, Sorocaba<\/li><li>Telefone para Reserva (15) 3032 1400<\/li><li>Tarifa Acordo = Di\u00e1ria Luxo Single: R$ 230,00<\/li><li>Tarifa Acordo = Di\u00e1ria Luxo Casal: R$ 280,00<\/li><li>Mencionar que \u00e9 para o Leil\u00e3o Vista Verde e Amigos<\/li><li>Dist\u00e2ncia Hotel x JCS &#8211; 21.6 km<\/li><\/ul>\n\n\n\n<p><strong><u>Sorocaba Park Hotel By Atlantica<\/u><\/strong><\/p>\n\n\n\n<ul><li>Endere\u00e7o: Av. Prof. Joaquim Silva 205 \u2013 Alto da Boa Vista, Sorocaba<\/li><li>Telefone para Reserva (15) 2102 2800<\/li><li>Tarifa Acordo &#8211; Luxo Twin Di\u00e1ria Single: R$ 280,00 (Sorocaba Park) +5% ISS<\/li><li>Tarifa Acordo \u2013 Luxo Twin Di\u00e1ria Casal: R$ 320,00 (Sorocaba Park) +5% ISS<\/li><li>Mencionar que \u00e9 para o Leil\u00e3o Vista Verde e Amigos<\/li><li>Dist\u00e2ncia Hotel x JCS &#8211; 24.4 km<\/li><\/ul>\n\n\n\n<p><strong><u>Grand Hotel Royal By Atlantica<\/u><\/strong><\/p>\n\n\n\n<ul><li>Endere\u00e7o: Rua Dr. \u00c1lvaro Soares 451- Centro, Sorocaba<\/li><li>Telefone para Reserva: (15) 2102 8903<\/li><li>Tarifa Acordo &#8211; Luxo Twin Di\u00e1ria Single: R$ 280,00 (Sorocaba Park) +5% ISS<\/li><li>Tarifa Acordo \u2013 Luxo Twin Di\u00e1ria Casal: R$ 320,00 (Sorocaba Park) +5% ISS<\/li><li>Mencionar que \u00e9 para o Leil\u00e3o Vista Verde e Amigos<\/li><li>Dist\u00e2ncia Hotel x JCS &#8211; 26.5 km<\/li><\/ul>\n\n\n\n<p><strong><u>Nacional Inn Sorocaba<\/u><\/strong><\/p>\n\n\n\n<ul><li>Endere\u00e7o: Rodovia Senador Jos\u00e9 Erm\u00edrio de Moraes, s\/n &#8211; Km 2,6 &#8211; Iporanga, Sorocaba<\/li><li>Telefone para Reserva (15) 3238 9800<\/li><li>Di\u00e1ria Single: R$ 158,00<br>Di\u00e1ria Casal:\u00a0 R$ 182,00<\/li><li>Di\u00e1ria Triplo: R$ 221,00<br>Mencionar que \u00e9 para o Leil\u00e3o Vista Verde e Amigos<\/li><li>Dist\u00e2ncia Hotel x JCS &#8211; 22.8 km<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dia 09\/03\/2024 &#8211; s\u00e1bado, acontecer\u00e1 o Leil\u00e3o Vista Verde &amp; Amigos 2024, no Jockey Club de Sorocaba, junto com as classificat\u00f3rias do GRANDE PR\u00caMIO &#8211; TORNEIO IN\u00cdCIO, e do GRANDE PR\u00caMIO I DERBY. O Torneio In\u00edcio \u00e9 para potros in\u00e9ditos e o I DERBY para cavalos de 3 ou mais anos, com bosa de R$ [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/22331"}],"collection":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/comments?post=22331"}],"version-history":[{"count":1,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/22331\/revisions"}],"predecessor-version":[{"id":22332,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/22331\/revisions\/22332"}],"wp:attachment":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/media?parent=22331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/categories?post=22331"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/tags?post=22331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}