﻿{"id":22194,"date":"2024-02-02T19:53:17","date_gmt":"2024-02-02T21:53:17","guid":{"rendered":"http:\/\/www.harasvistaverde.com.br\/blog\/?p=22194"},"modified":"2024-02-04T21:45:32","modified_gmt":"2024-02-04T23:45:32","slug":"revendo-amigos-no-royal-vista-ranch","status":"publish","type":"post","link":"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/02\/02\/revendo-amigos-no-royal-vista-ranch\/","title":{"rendered":"Revendo amigos no ROYAL VISTA RANCH"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/royal-1.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"403\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/royal-1.jpg\" alt=\"\" class=\"wp-image-22236\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/royal-1.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/royal-1-300x202.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Novamente muito bem recebidos no <strong>Royal Vista Ranch<\/strong>, que tem a <strong>Laura Erickson<\/strong>, como General Manager.<\/p>\n\n\n\n<p>Neste haras tivemos muita hist\u00f3ria em comum, pois eram s\u00f3cios de <strong>NO SECRETS HERE<\/strong>, e a casa dele quando em reprodu\u00e7\u00e3o nos EUA.<\/p>\n\n\n\n<p>A necessidade de visitar novamente o <strong>Royal Vista Ranch<\/strong> era grande, pois ali est\u00e3o entre muitos o pai e filho: <strong>APOLLITICAL JESS &amp; FLYING COWBOY 123.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1232.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"450\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1232.jpg\" alt=\"\" class=\"wp-image-22238\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1232.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1232-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><figcaption>FLYING COWBOY 123<\/figcaption><\/figure>\n\n\n\n<p>Entre ver cavalos e garanh\u00f5es, uma reuni\u00e3o, a pedido do <strong>Sr. Paulo Otavio<\/strong>, para tentar novas coberturas de <strong>FLYING COWBOY 123<\/strong> para o Brasil.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc123-1.jpg\" ><img loading=\"lazy\" width=\"500\" height=\"510\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc123-1.jpg\" alt=\"\" data-id=\"22239\" data-full-url=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc123-1.jpg\" data-link=\"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/02\/02\/revendo-amigos-no-royal-vista-ranch\/fc123-1\/\" class=\"wp-image-22239\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc123-1.jpg 500w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc123-1-294x300.jpg 294w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1233.jpg\" ><img loading=\"lazy\" width=\"598\" height=\"629\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1233.jpg\" alt=\"\" data-id=\"22240\" data-full-url=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1233.jpg\" data-link=\"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/02\/02\/revendo-amigos-no-royal-vista-ranch\/fc1233\/\" class=\"wp-image-22240\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1233.jpg 598w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/fc1233-285x300.jpg 285w\" sizes=\"(max-width: 598px) 100vw, 598px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Os novos propriet\u00e1rios deste garanh\u00e3o, com problemas anteriores com \u201cagentes\u201d, Centrais e Criadores do Brasil, definitivamente n\u00e3o querem mais neg\u00f3cio com brasileiros. Mas vamos aos cavalos l\u00e1 alojados:<\/p>\n\n\n\n<p><strong>APOLLITICAL JESS,<\/strong> o # 1 das estat\u00edsticas mundiais da atualidade: uma pintura. Lindo Cavalo. Sua cobertura para 2024 foi estabelecida em U$ 35.000 d\u00f3lares.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj2.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"450\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj2.jpg\" alt=\"\" class=\"wp-image-22242\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj2.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj2-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><figcaption>APOLLITICALJESS<\/figcaption><\/figure>\n\n\n\n<p>Em <strong>2023 foi o # 1 em Somas Ganhas de seus filhos, superando U$ 8.500.000<\/strong> de ganhos no ano, e acumulando <strong>U$ 66 milh\u00f5es<\/strong> de ganhos de seus filhos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj-1.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"547\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj-1.jpg\" alt=\"\" data-id=\"22243\" data-full-url=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj-1.jpg\" data-link=\"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/02\/02\/revendo-amigos-no-royal-vista-ranch\/aj-1\/\" class=\"wp-image-22243\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj-1.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj-1-300x274.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj3.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"519\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj3.jpg\" alt=\"\" data-id=\"22244\" data-full-url=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj3.jpg\" data-link=\"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/02\/02\/revendo-amigos-no-royal-vista-ranch\/aj3\/\" class=\"wp-image-22244\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj3.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/aj3-300x260.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Garanh\u00e3o l\u00edder por 12 vezes. Pai de ganhador do ALL AMERICAN FUTURITY, e \u00fanico a ultrapassar <strong>U$ 3 milh\u00f5es<\/strong> em ganhos: <strong>KJ DESPARADO<\/strong>.<\/p>\n\n\n\n<p>Pai de E<strong>MPRESSUM, APOLLITCAL BLOOD<\/strong> e muitos outros, inclusive <strong>FLYING COWBOY 123<\/strong>, a sensa\u00e7\u00e3o na reprodu\u00e7\u00e3o em 2023.<\/p>\n\n\n\n<p><strong>FLYING COWBOY 123,<\/strong> (veja post anterior), ficou em 4\u00ba lugar na estat\u00edstica geral por somas ganhas de seus filhos, com produ\u00e7\u00e3o de <strong>U$ 4,3 milh\u00f5es de d\u00f3lares <\/strong>na primeira gera\u00e7\u00e3o e m\u00e9dia de <strong>U$ 52.000 por filho corrido<\/strong> (a maior m\u00e9dia).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/flyinf-123.jpg\" ><img loading=\"lazy\" width=\"578\" height=\"715\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/flyinf-123.jpg\" alt=\"\" class=\"wp-image-22247\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/flyinf-123.jpg 578w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/flyinf-123-243x300.jpg 243w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure>\n\n\n\n<p>Seu filho <strong>COWBOYS GUN Z<\/strong>, venceu o <strong>ALL AMERICAN FUTURITY<\/strong> e foi eleito: <strong>CAMPE\u00c3O AQHA 2 ANOS<\/strong>.<\/p>\n\n\n\n<p>Dos garanh\u00f5es de primeira gera\u00e7\u00e3o<strong>, FLYING COWBOY 123 foi o # 1 com U$ 4,3 milh\u00f5es<\/strong> e o 2\u00ba colocado produziu ganhadores de U$ 300.000, para que se tenha uma ideia do que \u00e9 hoje <strong>FLYING COWBOY 123<\/strong>.<\/p>\n\n\n\n<p>A m\u00e9dia entre os 89 filhos dele vendidos em leil\u00e3o foi de <strong>U$ 68.845 ou seja R$ 350.000,00, \u00e0 vista.<\/strong><\/p>\n\n\n\n<p>Na sequ\u00eancia vimos <strong>APOLLITICAL BLOOD, <\/strong>ganhador de U$ 1.519.800 e tamb\u00e9m filho de <strong>APOLLITICAL JESS<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/ab3.jpg\" ><img loading=\"lazy\" width=\"600\" height=\"490\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/ab3.jpg\" alt=\"\" class=\"wp-image-22248\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/ab3.jpg 600w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/ab3-300x245.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p><strong>APOLLITICAL BLOOD<\/strong> costumo falar que \u00e9 da fam\u00edlia, afinal sua m\u00e3e \u00e9 BRAZILIAN DASHER, uma filha de <strong>FISHERS DASH<\/strong> na <strong>DINASTIA TOLL<\/strong>.<\/p>\n\n\n\n<p><strong>FISHERS DASH<\/strong>, que o Vista Verde importou para o Brasil com o Rancho das Am\u00e9ricas, e <strong>DINASTIA TOLL<\/strong> que \u00e9 filha de nossa <strong>PHILLIPS FILLY<\/strong> e \u00e9 irm\u00e3 de <strong>USA VISTA e XANGAI VISTA <\/strong>e irm\u00e3 de nossa <strong>KAPALUA SECRETS<\/strong>.<\/p>\n\n\n\n<p>Ainda conhecemos <strong>MR APOLLITICAL DASH<\/strong>, MR JESS PERRY x APOLLITICAL DASH por FIRST DOWN DASH.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/docs-1.jpg\" ><img loading=\"lazy\" width=\"400\" height=\"533\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/docs-1.jpg\" alt=\"\" data-id=\"22250\" data-full-url=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/docs-1.jpg\" data-link=\"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/02\/02\/revendo-amigos-no-royal-vista-ranch\/docs-1\/\" class=\"wp-image-22250\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/docs-1.jpg 400w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/docs-1-225x300.jpg 225w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">DOCS BEST CARD<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/maj.jpg\" ><img loading=\"lazy\" width=\"505\" height=\"548\" src=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/maj.jpg\" alt=\"\" data-id=\"22251\" data-full-url=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/maj.jpg\" data-link=\"http:\/\/www.harasvistaverde.com.br\/blog\/2024\/02\/02\/revendo-amigos-no-royal-vista-ranch\/maj\/\" class=\"wp-image-22251\" srcset=\"http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/maj.jpg 505w, http:\/\/www.harasvistaverde.com.br\/blog\/wp-content\/uploads\/2024\/02\/maj-276x300.jpg 276w\" sizes=\"(max-width: 505px) 100vw, 505px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">MR APOLLITICAL DASH<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><strong>DOCS BEST CARD<\/strong>, filho de CORONA CARTEL x DOCS FIRST CARD, por FIRST DOWN DASH, ganhador de U$ 784.318, vice campe\u00e3o no Los Alamitos Two Million Futurity, no Golden State Million Futurity, no Ed Burke Million Futurity e no Kindergarten Million Futurity.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novamente muito bem recebidos no Royal Vista Ranch, que tem a Laura Erickson, como General Manager. Neste haras tivemos muita hist\u00f3ria em comum, pois eram s\u00f3cios de NO SECRETS HERE, e a casa dele quando em reprodu\u00e7\u00e3o nos EUA. A necessidade de visitar novamente o Royal Vista Ranch era grande, pois ali est\u00e3o entre muitos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/22194"}],"collection":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/comments?post=22194"}],"version-history":[{"count":4,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/22194\/revisions"}],"predecessor-version":[{"id":22252,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/22194\/revisions\/22252"}],"wp:attachment":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/media?parent=22194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/categories?post=22194"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/tags?post=22194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}