﻿{"id":12762,"date":"2019-04-10T10:34:38","date_gmt":"2019-04-10T12:34:38","guid":{"rendered":"http:\/\/www.harasvistaverde.com.br\/blog\/?p=12762"},"modified":"2019-04-10T10:34:38","modified_gmt":"2019-04-10T12:34:38","slug":"palavra-presidente-jockey-club-de-sorocaba-informativo-6-2019","status":"publish","type":"post","link":"http:\/\/www.harasvistaverde.com.br\/blog\/2019\/04\/10\/palavra-presidente-jockey-club-de-sorocaba-informativo-6-2019\/","title":{"rendered":"Palavra do Presidente do Jockey Club de Sorocaba no Informativo # 6 &#8211; 2019"},"content":{"rendered":"<p>Tivemos a abertura oficial da Temporada no Jockey, no dia 16\/03, com as classificat\u00f3rias e depois, s\u00e1bado 30\/03, as primeiras finais dos Grande Pr\u00eamios Torneio In\u00edcio e Challenge. Corridas emocionantes, vibrantes, contagiantes.<\/p>\n<p>Em apenas duas reuni\u00f5es, j\u00e1 podemos sentir que a temporada toda ser\u00e1 excepcional, proporcionando FELICIDADE a todos os turfistas do Brasil e Am\u00e9rica do Sul que participam das corridas em nosso Jockey Club de Sorocaba ou nos acompanham pela internet.<\/p>\n<p>Agora, no dia 13\/04, chegou a vez do sensacional e imperd\u00edvel Grande Pr\u00eamio Brazilian Futurity com R$ 600.000,00 em pr\u00eamios &#8211; A MAIOR PREMIA\u00c7\u00c3O PARA O PRIMEIRO COLOCADO do turfe nacional, incluindo um carro 0Km ao treinador vencedor.<\/p>\n<p>Teremos tamb\u00e9m o GP Breeder\u2019s Derby &#8211; R$ 150.000,00 de bolsa, que promete ser um show incr\u00edvel com 7 Grandes Vencedores Cl\u00e1ssicos de 2018 e 2017.<\/p>\n<p>Estas duas provas contam com o patroc\u00ednio parcial do Haras Portofino, que tamb\u00e9m \u00e9 o patrocinador da Reforma do \u201cParquinho da Vila H\u00edpica\u201d que ser\u00e1 inaugurado com uma grande festa para a crian\u00e7ada, com sorvete, pipoca e algod\u00e3o doce.<\/p>\n<p>O Haras Porto Fino, tamb\u00e9m realiza seu Grande Leil\u00e3o em nosso Tattersall logo ap\u00f3s as corridas.<\/p>\n<p>No s\u00e1bado ainda, teremos a Grande final do Grande Pr\u00eamio Super Sprint, com R$ 200.000,00 de dota\u00e7\u00e3o. Um GP que j\u00e1 deixou todos ansiosos nas classificat\u00f3rias, com p\u00e1reos \u201cSuper\u201d (assim como o nome do GP) disputados. Imperd\u00edvel!<\/p>\n<p>Continuar\u00e1 o ano todo nosso trabalho pelo melhor do esporte, das corridas justas, onde vence o melhor conjunto.<\/p>\n<p>Estamos colocando o Jockey Club de Sorocaba num padr\u00e3o de seriedade dentro dos maiores padr\u00f5es de qualidade no mundo. Sa\u00edmos de ser um clube fechado, para atingir toda popula\u00e7\u00e3o Turf\u00edsticas, amantes do cavalo em geral, apostadores e as pessoas de toda a regi\u00e3o.<\/p>\n<p>A contrata\u00e7\u00e3o do dr. Thomas Wolff (maior sumidade no controle antidoping), nos d\u00e1 toda seguran\u00e7a jur\u00eddica e do bem-estar animal.<\/p>\n<p>Na semana passada, foi dado mais um passo importante pela Comiss\u00e3o de Corridas, que, com muita coragem e determina\u00e7\u00e3o, revogou qualquer delibera\u00e7\u00e3o anterior, que pudesse vincular os envios de materiais para exames em qualquer laborat\u00f3rio pr\u00e9-indicado, refor\u00e7ando que o quesito SURPRESA \u00e9 o mais eficaz elemento para evitar que se utilize medicamentos proibidos.<\/p>\n<p>Ningu\u00e9m sabe onde est\u00e3o os radares m\u00f3veis e eles evitam acidentes. Ningu\u00e9m sabe onde estar\u00e3o as \u201cblitz com baf\u00f4metro\u201d e elas evitam acidentes, pois a surpresa faz com que as pessoas cumpram as regras. Ningu\u00e9m precisa saber em qual laborat\u00f3rio ser\u00e3o feitos os exames do Jockey e sim que n\u00e3o se deve usar medicamentos proibidos, evitando acidentes e protegendo o cavalo.<\/p>\n<p>Os preparativos para o LEIL\u00c3O MIXED SALE do Jockey Club de Sorocaba, est\u00e3o a pleno vapor.<\/p>\n<p>Todos os MAIS IMPORTANTES CRIADORES, j\u00e1 est\u00e3o doando coberturas de seus garanh\u00f5es, ventres e embri\u00f5es, para serem comercializados e ajudarem o Jockey a continuar sendo refer\u00eancia mundial. Agradecemos todos os participantes. FA\u00c7A sua doa\u00e7\u00e3o. Fale com nosso escrit\u00f3rio para participar desta grande festa.<\/p>\n<p>Sejam todos bem-vindos! Desejamos a todos um \u00f3timo espet\u00e1culo.<\/p>\n<p>Forte abra\u00e7o,<\/p>\n<p>Mauro Eli Zaborowsky &#8211; Presidente Jockey Club de Sorocaba<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tivemos a abertura oficial da Temporada no Jockey, no dia 16\/03, com as classificat\u00f3rias e depois, s\u00e1bado 30\/03, as primeiras finais dos Grande Pr\u00eamios Torneio In\u00edcio e Challenge. Corridas emocionantes, vibrantes, contagiantes. Em apenas duas reuni\u00f5es, j\u00e1 podemos sentir que a temporada toda ser\u00e1 excepcional, proporcionando FELICIDADE a todos os turfistas do Brasil e Am\u00e9rica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[1786,2068],"_links":{"self":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/12762"}],"collection":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/comments?post=12762"}],"version-history":[{"count":1,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/12762\/revisions"}],"predecessor-version":[{"id":12763,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/posts\/12762\/revisions\/12763"}],"wp:attachment":[{"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/media?parent=12762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/categories?post=12762"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.harasvistaverde.com.br\/blog\/wp-json\/wp\/v2\/tags?post=12762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}